{"id":1133,"date":"2019-11-15T22:36:00","date_gmt":"2019-11-15T22:36:00","guid":{"rendered":"https:\/\/edicionesmasqueoca.com\/diarios\/?p=1133"},"modified":"2022-05-15T22:37:01","modified_gmt":"2022-05-15T22:37:01","slug":"actualizacion-6-high-frontier-4-all","status":"publish","type":"post","link":"https:\/\/edicionesmasqueoca.com\/diarios\/2019\/11\/15\/actualizacion-6-high-frontier-4-all\/","title":{"rendered":"ACTUALIZACI\u00d3N #6 &#8211; \u00abHigh Frontier 4 All\u00bb"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">\u00daltimas Horas, Stretch Goals, Huevos de Pascua y Ediciones en Otros Idiomas<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nos acercamos al destino final del Kickstarter. Pero \u00e9ste est\u00e1 lejos del destino final para High Frontier y sus m\u00f3dulos. Continuar\u00e1 su viaje durante muchos a\u00f1os. M\u00e1s informaci\u00f3n en futuras actualizaciones.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00daltimos Stretch Goals<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Hemos revelado los stretch goals finales. Y se han desbloqueado todos los stretch goals anteriores. Entre los nuevos stretch goals tenemos un nivel especial, 308,700 USD, celebrando que este es un nuevo r\u00e9cord para nosotros. Y en ese stretch goals hemos a\u00f1adido una segunda ayuda para el jugador. La ayuda del jugador en High Frontier 4 All es una creaci\u00f3n de 6 p\u00e1ginas plegadas en Z, creada por Geoff Speare. Estamos muy contentos con el resultado y esperamos que a todos os guste.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n se han desbloqueado m\u00e1s minis 3d de estaciones espaciales (310.000). En los 340.000 desbloquearemos que todas las tarjetas sean de 350 g\/m2. En 370.000 vamos a actualizar los dados al doble del volumen (de 12 a 16 mm de lado).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, si llegamos a 400.000, a\u00f1adiremos otro jugador al juego. Se trata de una gran actualizaci\u00f3n que afecta a muchos componentes, pero si llegamos tan lejos, queremos recompensar el juego con este importante coste de producci\u00f3n adicional.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Huevos de Pascua<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de que Pawel se encargue de revisar los env\u00edos de Huevos de Pascua, en una actualizaci\u00f3n despu\u00e9s del Kickstarter revelaremos qui\u00e9n ten\u00eda los ojos y la mente m\u00e1s aguda para este desaf\u00edo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00daltimas horas<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Las horas finales son una parte importante y emocionante de un Kickstarter. Vamos a impulsar la campa\u00f1a a\u00f1adiendo publicidad adicional en varios medios sociales, a\u00f1adiendo banners adicionales a Boardgamegeek, publicando un n\u00famero de nuestro bolet\u00edn informativo para todos los suscriptores, etc. Pod\u00e9is ayudar haciendo lo mismo \ud83d\ude42<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Selecciona el idioma correcto<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Estamos muy contentos y agradecidos de haber podido atraer a tantos editores a la campa\u00f1a para las versiones en otros idiomas. Si est\u00e1s interesado en el juego en otro idioma que no sea el ingl\u00e9s, recuerda elegir la aportaci\u00f3n para esa versi\u00f3n del juego. Tambi\u00e9n buscamos activamente m\u00e1s editores interesados en licenciar el juego en otros idiomas y \u00e1reas geogr\u00e1ficas. Si conoces a alguien interesado, p\u00eddele que se ponga en contacto con pal.keller@iongamedesign.com<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n nos gustar\u00eda agradeceros todos los comentarios interesantes, divertidos e inteligentes que nos hab\u00e9is dejado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\/Besime &amp; Jon<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00daltimas Horas, Stretch Goals, Huevos de Pascua y Ediciones en Otros Idiomas Nos acercamos al destino final del Kickstarter. Pero \u00e9ste est\u00e1 lejos del destino final para High Frontier y sus m\u00f3dulos. Continuar\u00e1 su viaje durante muchos a\u00f1os. M\u00e1s informaci\u00f3n en futuras actualizaciones. \u00daltimos Stretch Goals Hemos revelado los stretch goals finales. Y se han [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":998,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1133","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-highfrontier4all","entry","has-media"],"_links":{"self":[{"href":"https:\/\/edicionesmasqueoca.com\/diarios\/wp-json\/wp\/v2\/posts\/1133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/edicionesmasqueoca.com\/diarios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/edicionesmasqueoca.com\/diarios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/edicionesmasqueoca.com\/diarios\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/edicionesmasqueoca.com\/diarios\/wp-json\/wp\/v2\/comments?post=1133"}],"version-history":[{"count":1,"href":"https:\/\/edicionesmasqueoca.com\/diarios\/wp-json\/wp\/v2\/posts\/1133\/revisions"}],"predecessor-version":[{"id":1134,"href":"https:\/\/edicionesmasqueoca.com\/diarios\/wp-json\/wp\/v2\/posts\/1133\/revisions\/1134"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/edicionesmasqueoca.com\/diarios\/wp-json\/wp\/v2\/media\/998"}],"wp:attachment":[{"href":"https:\/\/edicionesmasqueoca.com\/diarios\/wp-json\/wp\/v2\/media?parent=1133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/edicionesmasqueoca.com\/diarios\/wp-json\/wp\/v2\/categories?post=1133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/edicionesmasqueoca.com\/diarios\/wp-json\/wp\/v2\/tags?post=1133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}