{"id":1937,"date":"2020-03-29T00:16:00","date_gmt":"2020-03-29T00:16:00","guid":{"rendered":"https:\/\/edicionesmasqueoca.com\/diarios\/?p=1937"},"modified":"2022-05-26T00:20:19","modified_gmt":"2022-05-26T00:20:19","slug":"campeones-de-midgar-big-box-en-espanol","status":"publish","type":"post","link":"https:\/\/edicionesmasqueoca.com\/diarios\/2020\/03\/29\/campeones-de-midgar-big-box-en-espanol\/","title":{"rendered":"CAMPEONES DE MIDGAR: BIG BOX EN ESPA\u00d1OL"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"357\" src=\"https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Logo.jpg\" alt=\"\" class=\"wp-image-1938\" srcset=\"https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Logo.jpg 640w, https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Logo-300x167.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure>\n<\/div>\n\n\n<p><em>El sistema de Reserva Anticipada de MasQueOca Ediciones consiste en la presentaci\u00f3n gradual de un proyecto, a medida que este avanza y se est\u00e1 trabajando en \u00e9l, de manera que aquellos que reservan el juego no solo se beneficiar\u00e1n de descuentos adicionales por reserva anticipada, sino que adem\u00e1s ser\u00e1n part\u00edcipes directos de su desarrollo y podr\u00e1n intervenir en el resultado final del juego.&nbsp;&nbsp;<\/em><em>Adem\u00e1s, si el proyecto as\u00ed lo plantea, conseguir\u00e1n elementos exclusivos y limitados para premiar su confianza y ser\u00e1n los primeros en recibir su copia en cuanto el juego llegue a nuestro almac\u00e9n.<\/em><\/p>\n\n\n\n<p><em>A medida que las reservas vayan aumentando, se podr\u00e1n ir desbloqueando mejoras adicionales que ser\u00e1n a\u00f1adidas a todas las copias del juego (incluyendo la versi\u00f3n final para distribuci\u00f3n a tiendas).&nbsp;<\/em><em>El objeto de este sistema es traer a nuestro idioma t\u00edtulos cuyas especiales caracter\u00edsticas (de edici\u00f3n, venta, distribuci\u00f3n), hacen muy complicado el planteamiento de una edici\u00f3n est\u00e1ndar. Tambi\u00e9n tiene la intenci\u00f3n de acercar el funcionamiento interno del editorial al cliente final (compartiendo informaci\u00f3n sobre diversos temas tales como el proceso de dise\u00f1o, edici\u00f3n, etc.).<\/em><\/p>\n\n\n\n<p><strong>\u00bfC\u00f3mo funciona?&nbsp;<\/strong><\/p>\n\n\n\n<p>El sistema MQORA funciona de la siguiente manera:<\/p>\n\n\n\n<p>-Durante un per\u00edodo de tiempo concreto, el juego en cuesti\u00f3n ser\u00e1 ofertado con un descuento determinado. Esto ser\u00e1 anunciando en el blog del juego y todos los per\u00edodos y fechas quedar\u00e1n claramente reflejadas.&nbsp;<\/p>\n\n\n\n<p>-Para realizar la reserva en esas condiciones, solo ser\u00e1 necesario realizar la compra del producto a trav\u00e9s del enlace facilitado. Todas las reservas anticipadas recibidas dentro del per\u00edodo del enlace de reserva activo se consideran v\u00e1lidas. Recibir\u00e1s un email de confirmaci\u00f3n con tu pedido, d\u00f3nde se te indicar\u00e1 la cantidad a abonar. Todos los pedidos no abonados antes del l\u00edmite establecido ser\u00e1n anulados.<\/p>\n\n\n\n<p>-La Reserva Anticipada debe ser abonada mediante transferencia bancaria, tarjeta de cr\u00e9dito o PayPal, antes de que finalice cada uno de los per\u00edodos establecidos. La opci\u00f3n de pago contra reembolso no est\u00e1 disponible bajo este sistema.&nbsp;<\/p>\n\n\n\n<p>-El descuento de la Reserva Anticipada ser\u00e1 menor a medida que se desbloquee contenido adicional, se incorporen mejoras en los componentes o se acerque el momento de que el juego entre en producci\u00f3n (momento en el cual el per\u00edodo de Reserva Anticipada finalizar\u00e1).<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/portada-midgard.jpg\" alt=\"\" class=\"wp-image-1587\" width=\"460\" height=\"457\" srcset=\"https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/portada-midgard.jpg 505w, https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/portada-midgard-300x298.jpg 300w, https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/portada-midgard-150x150.jpg 150w\" sizes=\"(max-width: 460px) 100vw, 460px\" \/><\/figure>\n<\/div>\n\n\n<p><em>El Jarl de Trondheim ha muerto&#8230;<\/em><\/p>\n\n\n\n<p><em>Sin un liderazgo fuerte, su pr\u00f3spero reino est\u00e1 indefenso. Incontables criaturas que antes tem\u00edan al poderoso l\u00edder, han aprovechado esta debilidad en Midgard y est\u00e1n atacando en manadas, llevando el caos y destrucci\u00f3n con ellos. Los trolls atacan la ciudad. Los Draugr aterrorizan a los pueblos cercanos. Los monstruos atacan a viajeros y comerciantes por igual. La gente est\u00e1 sufriendo y necesita un campe\u00f3n. En Champions of Midgard, eres un l\u00edder vikingo que busca ganar gloria para tu clan. Derrota a los trolls para mantener a la gente del pueblo de tu lado. Mata a Draugr para ganar oro y poder financiar tus expediciones. Mata monstruos en sus guaridas para ganar la Gloria y el favor del dioses. Al derrotar a estas criaturas \u00e9picas, demostrar\u00e1s que eres digno de convertirte en el nuevo Jarl. y ser proclamado como un Campe\u00f3n de Midgard<\/em><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"512\" height=\"261\" src=\"https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Desplegado-1.jpg\" alt=\"\" class=\"wp-image-1939\" srcset=\"https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Desplegado-1.jpg 512w, https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Desplegado-1-300x153.jpg 300w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure>\n<\/div>\n\n\n<p>Campeones de Midgard Big Box es un juego para 2 a 5 jugadores en el que a lo largo de 8 rondas tratar\u00e1s de convertirte en el Campe\u00f3n de Midgard, acumulando la mayor cantidad posible de gloria. Para ello, los jugadores colocar\u00e1n a sus trabajadores en las distintas localizaciones del mapa con el fin de obtener distintos recursos, con el fin de equipar a sus guerreros. Se pueden encontrar localizaciones como los astilleros, el mercado, el forjador de runas, la herrer\u00eda&#8230; cada localizaci\u00f3n es diferente, y todas ellas importantes. Por desgracia, una vez que un jugador se ha colocado en una, esta permanecer\u00e1 ocupada e inaccesible al resto de jugadores durante la ronda, por lo que la planificaci\u00f3n es muy importante<br><\/p>\n\n\n\n<p>Por otro lado, los jugadores tendr\u00e1n que enfrentarse a las distintas criaturas que atacan la ciudad. El objetivo principal del juego es ganar la gloria que se puede conseguir gracias a los combates. Una vez que todos los trabajadores han sido colocados en las localizaciones del mapa, tienen lugar los enfrentamientos contra las m\u00edticas criaturas. Aquellos jugadores que hayan enviado guerreros al combate, lanzar\u00e1n sus dados para tratar de derrotarlos.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Dados-1.jpg\" alt=\"\" class=\"wp-image-1940\" srcset=\"https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Dados-1.jpg 400w, https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Dados-1-300x300.jpg 300w, https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Dados-1-150x150.jpg 150w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/figure>\n<\/div>\n\n\n<p>Por si esto fuera poco, hay un elemento a\u00f1adido que empieza a cobrar peso en la segunda mitad del juego: navegar a tierras lejanas para continuar con las famosas expediciones de conquista que convirtieron al pueblo vikingo en uno de los m\u00e1s temidos de la \u00e9poca. La comparativa con juegos tan ic\u00f3nicos como Stone Age o Lord of Waterdeep es inevitable, y es que la simpleza y sencillez de las mec\u00e1nicas de Champions of Midgard lo convierten en un juego ideal para todo tipo de p\u00fablico, sin descuidar el apartado de gesti\u00f3n y estrategia propia de los juegos de colocaci\u00f3n de trabajadores que acaparan las mejores cr\u00edticas del mercado actual.<\/p>\n\n\n\n<p><strong>CAMPEONES DE MIDGARD: BIG BOX<\/strong><\/p>\n\n\n\n<p>La versi\u00f3n Big Box de Campeones de Midgard en Espa\u00f1ol incluye, en una sola caja, el siguiente contenido:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>1 tablero de juego<\/li><li>1 tablero de expansi\u00f3n: Las Monta\u00f1as Oscuras<\/li><li>1 tablero de expansi\u00f3n: Valhalla<\/li><li>10 planchas de cart\u00f3n troqueladas con m\u00e1s de 300 fichas de juego<\/li><li>183 cartas de tama\u00f1o est\u00e1ndar<\/li><li>92 cartas de tama\u00f1o usa mini<\/li><li>71 dados personalizados<\/li><li>20 piezas de madera (con forma tronco)<\/li><li>30 piezas de comida (con forma muslito de pollo)<\/li><li>25 meeples vikingos (con cuernos, como manda el mito)<\/li><li>5 discos de madera<\/li><li>5 marcadores de victoria (cascos con cuernos)<\/li><li>34 monedas de madera<\/li><li>28 piezas de favor de madera (con forma de cuerno)<\/li><li>19 marcadores de culpa de madera (con forma de monstruo)<\/li><li>3 fichas de da\u00f1o de madera (con forma de gota de sangre)<\/li><li>1 marcador de turno de madera<\/li><li>1 hoja de pegatinas para los marcadores de culpa y monedas de madera<\/li><li>1 hoja de reglas del contenido promocional<\/li><li>3 reglamentos de 16 p\u00e1ginas<\/li><li>2 insertos de juego de pl\u00e1stico especiales para ordenar todo el contenido<\/li><li>Contenido promocional original y contenido promocional exclusivo\u00a0<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"256\" src=\"https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Promos-Champions.jpg\" alt=\"\" class=\"wp-image-1941\" srcset=\"https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Promos-Champions.jpg 640w, https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Promos-Champions-300x120.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<p><strong>EL VALOR DE TODO EL CONTENIDO\u00a0PROMOCIONAL Y LOS ELEMENTOS<\/strong> <strong>TEM\u00c1TICOS DE MADERA ES DE M\u00c1S DE 75\u20ac<\/strong><br>A continuaci\u00f3n, se muestran algunas im\u00e1genes del contenido promocional as\u00ed como algunas ilustraciones originales de las promos exclusivas de la versi\u00f3n Big Box en Espa\u00f1ol. en pr\u00f3ximas actualizaciones, encontrar\u00e9is todas las ilustraciones finales de las cartas y personajes exclusivos de la versi\u00f3n Big Box en espa\u00f1ol, con sus habilidades y un breve trasfondo hist\u00f3rico de las mismas.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"212\" height=\"320\" data-id=\"1946\" src=\"https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Despreciado.jpg\" alt=\"\" class=\"wp-image-1946\" srcset=\"https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Despreciado.jpg 212w, https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Despreciado-199x300.jpg 199w\" sizes=\"(max-width: 212px) 100vw, 212px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"288\" height=\"400\" data-id=\"1944\" src=\"https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Draudan.jpg\" alt=\"\" class=\"wp-image-1944\" srcset=\"https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Draudan.jpg 288w, https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Draudan-216x300.jpg 216w\" sizes=\"(max-width: 288px) 100vw, 288px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"426\" height=\"640\" data-id=\"1942\" src=\"https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/LAGHERTHA.jpg\" alt=\"\" class=\"wp-image-1942\" srcset=\"https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/LAGHERTHA.jpg 426w, https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/LAGHERTHA-200x300.jpg 200w\" sizes=\"(max-width: 426px) 100vw, 426px\" \/><figcaption>Ilustraci\u00f3n de Lathgertha, uno de los personajes exclusivos de la versi\u00f3n Big Box en espa\u00f1ol (por David Lanza)<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"426\" height=\"640\" data-id=\"1943\" src=\"https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/MARTINICO-1.jpg\" alt=\"\" class=\"wp-image-1943\" srcset=\"https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/MARTINICO-1.jpg 426w, https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/MARTINICO-1-200x300.jpg 200w\" sizes=\"(max-width: 426px) 100vw, 426px\" \/><figcaption>Ilustraci\u00f3n del Martinico, uno de los monstruos exclusivos de la versi\u00f3n Big Box en espa\u00f1ol (por David Lanza)<br><\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"288\" height=\"400\" data-id=\"1947\" src=\"https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Meeple-Gigante.jpg\" alt=\"\" class=\"wp-image-1947\" srcset=\"https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Meeple-Gigante.jpg 288w, https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Meeple-Gigante-216x300.jpg 216w\" sizes=\"(max-width: 288px) 100vw, 288px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"288\" height=\"400\" data-id=\"1945\" src=\"https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Rey-Bergrisar.jpg\" alt=\"\" class=\"wp-image-1945\" srcset=\"https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Rey-Bergrisar.jpg 288w, https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Rey-Bergrisar-216x300.jpg 216w\" sizes=\"(max-width: 288px) 100vw, 288px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"283\" height=\"400\" data-id=\"1948\" src=\"https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Seezam.jpg\" alt=\"\" class=\"wp-image-1948\" srcset=\"https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Seezam.jpg 283w, https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Seezam-212x300.jpg 212w\" sizes=\"(max-width: 283px) 100vw, 283px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"209\" height=\"320\" data-id=\"1949\" src=\"https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Viaje-de-Odin.jpg\" alt=\"\" class=\"wp-image-1949\" srcset=\"https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Viaje-de-Odin.jpg 209w, https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Viaje-de-Odin-196x300.jpg 196w\" sizes=\"(max-width: 209px) 100vw, 209px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"211\" height=\"320\" data-id=\"1950\" src=\"https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Virtud.jpg\" alt=\"\" class=\"wp-image-1950\" srcset=\"https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Virtud.jpg 211w, https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Virtud-198x300.jpg 198w\" sizes=\"(max-width: 211px) 100vw, 211px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"208\" data-id=\"1951\" src=\"https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Componentes-de-Madera.jpg\" alt=\"\" class=\"wp-image-1951\" srcset=\"https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Componentes-de-Madera.jpg 640w, https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Componentes-de-Madera-300x98.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><figcaption>Piezas de madera tem\u00e1ticas con las pegatinas incluidas en el juego<br><\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"445\" height=\"256\" data-id=\"1952\" src=\"https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Componentes-especiales-de-Madera.jpg\" alt=\"\" class=\"wp-image-1952\" srcset=\"https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Componentes-especiales-de-Madera.jpg 445w, https:\/\/edicionesmasqueoca.com\/diarios\/wp-content\/uploads\/2022\/05\/Componentes-especiales-de-Madera-300x173.jpg 300w\" sizes=\"(max-width: 445px) 100vw, 445px\" \/><figcaption>Piezas de madera tem\u00e1ticas (lanzadas en exclusiva a trav\u00e9s de Kickstarter en la versi\u00f3n Jarl Edition)<br><\/figcaption><\/figure>\n<\/figure>\n\n\n\n<p><strong>COMPARATIVA DE COSTES RESPECTO A LA VERSI\u00d3N ORIGINAL<\/strong><br>Hemos ajustado al m\u00e1ximo posible el precio de la versi\u00f3n Big Box e incluido todo el contenido promocional original que ha sido posible. Para aquellos casos en los que no hemos podido adquirir dicho contenido, hemos creado nuestro propio contenido (aprobado por el editor original), para que esta versi\u00f3n Big Box sea la versi\u00f3n definitiva para un juego de esta categor\u00eda. Campeones de Midgard est\u00e1 posicionado en el ranking mundial seg\u00fan la web www.boardgamegeek.com en el puesto 92 a nivel general y en el puesto 77 como juego estrat\u00e9gico. El precio del contenido original seg\u00fan la propia web del editor es el siguiente (comprobable en la propia web del editor&nbsp;https:\/\/www.greyfoxgames.com\/?s=champions+of+midgard&amp;post_type=product):<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Juego base: 59,99 usd<\/li><li>Expansi\u00f3n Dark Mountains: 24,99 usd<\/li><li>Expansi\u00f3n Valhalla: 29,99 usd<\/li><li>Mejora de meeples y marcadores de puntuaci\u00f3n tem\u00e1ticos: 9,99 usd<\/li><li>Mejora de recursos de madera y comida tem\u00e1ticos: 9,99 usd<\/li><li>Mejora de monedas, marcadores de culpa, fichas de favor, ronda y da\u00f1o: 19,99 usd<\/li><li>Promos de Seezam, Virtud, Despreciado y Prueba de Od\u00edn: 6,99 usd<\/li><li>Promos de Draudan y Rey Bergrisar: 5,99 usd<\/li><li>Promo Meeple Monster: \u00a1AGOTADA! (se vende de segunda mano por 25,00 usd), pero computamos en el total como 2,99 usd (equivalente a SeeZam cuando se vende por separado del pack anterior)<\/li><li>Personaje Bjorn Hammerblow (reemplazado por Ragnar El Conquistador): 4,99 usd<\/li><li>Personaje Jalev (reemplazado por Lathgertha, Skjalmo Legendario); 4,99 usd<\/li><li>Chinesee Monsters (reemplazados por el pack Spanish Monsters): 4,99 usd<\/li><li>Valkierie Blesings &amp; Sikling Epic Monster (reemplazados por 2 monstruos \u00e9picos espa\u00f1oles): 4,99 usd<\/li><li>Nuberu Errante, Favor del Jarl, Runoca, Maestr\u00eda: No tienen equivalente con otras promos originales \u00a1pero las hemos a\u00f1adido!, siguiendo el esquema de precios del editor original, su coste ser\u00eda equivalente al pack de SeeZam: 6,99 usd<\/li><\/ul>\n\n\n\n<p><strong>PRECIO TOTAL: 197,86 usd (unos 177,16\u20ac el cambio)<\/strong><\/p>\n\n\n\n<p><strong>\u00a1Consigue ahora tu versi\u00f3n Big Box en espa\u00f1ol por 90\u20ac y transporte incluido! V\u00e1lido hasta el d\u00eda 15 de Abril.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El sistema de Reserva Anticipada de MasQueOca Ediciones consiste en la presentaci\u00f3n gradual de un proyecto, a medida que este avanza y se est\u00e1 trabajando en \u00e9l, de manera que aquellos que reservan el juego no solo se beneficiar\u00e1n de descuentos adicionales por reserva anticipada, sino que adem\u00e1s ser\u00e1n part\u00edcipes directos de su desarrollo y [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1938,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[35],"tags":[],"class_list":["post-1937","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-campeones-de-midgard","entry","has-media"],"_links":{"self":[{"href":"https:\/\/edicionesmasqueoca.com\/diarios\/wp-json\/wp\/v2\/posts\/1937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/edicionesmasqueoca.com\/diarios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/edicionesmasqueoca.com\/diarios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/edicionesmasqueoca.com\/diarios\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/edicionesmasqueoca.com\/diarios\/wp-json\/wp\/v2\/comments?post=1937"}],"version-history":[{"count":1,"href":"https:\/\/edicionesmasqueoca.com\/diarios\/wp-json\/wp\/v2\/posts\/1937\/revisions"}],"predecessor-version":[{"id":1953,"href":"https:\/\/edicionesmasqueoca.com\/diarios\/wp-json\/wp\/v2\/posts\/1937\/revisions\/1953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/edicionesmasqueoca.com\/diarios\/wp-json\/wp\/v2\/media\/1938"}],"wp:attachment":[{"href":"https:\/\/edicionesmasqueoca.com\/diarios\/wp-json\/wp\/v2\/media?parent=1937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/edicionesmasqueoca.com\/diarios\/wp-json\/wp\/v2\/categories?post=1937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/edicionesmasqueoca.com\/diarios\/wp-json\/wp\/v2\/tags?post=1937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}